{"id":38726,"date":"2022-04-05T15:47:37","date_gmt":"2022-04-05T15:47:37","guid":{"rendered":"https:\/\/femivoz.es\/feminizacion-de-la-comunicacion-oral-y-particularmente-de-la-voz\/"},"modified":"2022-06-08T21:57:54","modified_gmt":"2022-06-08T21:57:54","slug":"feminiser-la-communication-orale-et-plus-specifiquement-la-voix","status":"publish","type":"post","link":"https:\/\/femivoz.es\/fr\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\/","title":{"rendered":"F\u00e9miniser la communication orale et plus sp\u00e9cifiquement la voix"},"content":{"rendered":"\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-cover\" style=\"min-height:154px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-100 has-background-dim\" style=\"background-color:#6e7171\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<p><strong><span style=\"color: #ffffff;\"><em>\u00ab\u00a0Cet article vise \u00e0 \u00e9clairer vos connaissances dans le domaine de f\u00e9minisation vocale dont l\u2019efficacit\u00e9 reste encore un champ d\u2019investigation trop peu explor\u00e9.\u00a0\u00bb<\/em><\/span><\/strong><\/p>\n<\/div><\/div>\n\n\n<p style=\"text-align: justify;\"><b>Batoul JABER\u00b9<\/b><b>,\u00b2 <\/b><b>&amp; Dominique MORSOMME<\/b><b>\u00b2<\/b><span style=\"font-weight: 400;\">,<\/span><\/p>\n<p style=\"text-align: justify;\"><i><span style=\"font-weight: 400;\">\u00b9Universit\u00e9 Saint Joseph de Beyrouth, Liban<\/span><\/i><i><span style=\"font-weight: 400;\">&nbsp;;<\/span><\/i><\/p>\n<p style=\"text-align: justify;\"><i><span style=\"font-weight: 400;\">\u00b2Research Unit for a life-Course perspective on Health and Education, Universit\u00e9 de Li\u00e8ge, Belgique<\/span><\/i><\/p>\n<p style=\"text-align: justify;\">\n<\/p><p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Article publi\u00e9 initialement sur UPLF <\/span><a href=\"https:\/\/www.uplf.be\/\"><span style=\"font-weight: 400;\">https:\/\/www.uplf.be\/<\/span><\/a><span style=\"font-weight: 400;\"> &#8211;<\/span><span style=\"font-weight: 400;\">&nbsp;IU n\u00ba 5\/2021.<\/span><\/p>\n\n\n<div style=\"height:23px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Nous tenons \u00e0 remercier chaleureusement les \u00e9tudiants pour les \u00e9tudes qu\u2019ils ont men\u00e9es dans le cadre de leur m\u00e9moire. Sans eux, nous n\u2019\u00e9cririons pas la m\u00eame histoire.<\/span><\/p>\n\n\n<figure class=\"wp-block-image alignleft size-full\"><a href=\"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/Sans-titre.png\"><img decoding=\"async\" width=\"111\" height=\"218\" src=\"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/Sans-titre.png\" alt=\"\" class=\"wp-image-38711\"\/><\/a><\/figure>\n\n\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Depuis quelques ann\u00e9es, les demandes de f\u00e9minisation vocale aupr\u00e8s des logop\u00e8des sp\u00e9cialis\u00e9(e)s en voix augmentent, et ce, particuli\u00e8rement de la part des femmes transgenres (Hancock &amp; Helenius, 2012). Le DSM-V d\u00e9finit la dysphorie de genre en \u00e9tant \u00ab une non-congruence marqu\u00e9e entre le genre v\u00e9cu\/exprim\u00e9 par la personne et le genre assign\u00e9. Il s\u2019agit d\u2019un d\u00e9sir marqu\u00e9 d\u2019appartenir \u00e0 l\u2019autre genre ou \u00e0 un genre diff\u00e9rent de celui qui lui est assign\u00e9 \u00bb (T\u2019Sjoen et al., 2019 ; P\u00e9piot,2013). Aussi, depuis 2013, l\u2019association am\u00e9ricaine de psychiatrie insiste sur le fait que \u00ab la non-conformit\u00e9 de genre \u00bb n\u2019est pas un trouble mental (S\u00f6dersten et al., 2019). Ainsi, les personnes pr\u00e9sentant une dysphorie de genre ne sont plus reconnues comme \u00e9tant dans un \u00e9tat de recherche identitaire. En effet, les personnes transgenres affirment \u00eatre soit \u00ab une femme dans un corps d\u2019homme \u00bb (femme transgenre) soit \u00ab un homme dans un corps de femme \u00bb (homme transgenre). Certaines d\u2019entre elles souhaitent aussi effectuer un changement ou une transition de sexe (Bourgeois, 1980). Celui-ci consiste en un processus long et complexe n\u00e9cessitant un suivi pluridisciplinaire individualis\u00e9 visant \u00e0 assurer une qualit\u00e9 de vie optimale, r\u00e9pondant aux besoins des personnes pr\u00e9sentant une dysphorie. D\u00e8s \u00e0 pr\u00e9sent, il est \u00e9galement d\u00e9montr\u00e9 que le genre vocal participe significativement \u00e0 leur qualit\u00e9 de vie (Coleman et al., 2012).&nbsp;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Pour certaines personnes transgenres, la voix s\u2019av\u00e8re un aspect indispensable \u00e0 envisager dans le principe de transition puisqu\u2019elle consiste en un enjeu psychologique et communicationnel important participant \u00e0 leur insertion sociale (Lechien et al., 2014). Au sein de la population transgenre, nous observons que les femmes transgenres consultent plus les cabinets de logop\u00e9die que les hommes transgenres, \u00e0 la recherche d\u2019une modification des param\u00e8tres de leur voix. Cela s\u2019explique en partie par l\u2019efficacit\u00e9 de la prise de testost\u00e9rone qui permet un \u00e9paississement de la masse musculaire des plis vocaux, entra\u00eenant une baisse de la fr\u00e9quence fondamentale (fo) et une voix plus masculine (Azul, Neuschaefer-Rube, Nygren et S\u00f6dersten, 2017). Ceci n\u2019est pas le cas chez les femmes, pour qui l\u2019hormonoth\u00e9rapie ne modifie pas les param\u00e8tres vocaux, d\u2019o\u00f9 le recours \u00e0 la f\u00e9minisation vocale. Les s\u00e9ances de th\u00e9rapie vocale deviennent alors pour certaines une \u00e9tape indispensable au sein de leur transition, sachant que la satisfaction des femmes transgenres concernant leur voix et l\u2019ad\u00e9quation de celle-ci avec l\u2019id\u00e9e qu\u2019elles se font du genre f\u00e9minin, est un indice de bonne qualit\u00e9 de vie. Dans cette optique, trois possibilit\u00e9s s\u2019offrent \u00e0 toute personne d\u00e9sireuse de f\u00e9miniser sa voix : la chirurgie, la th\u00e9rapie vocale ou une combinaison des deux (Wylie et al., 2014 ; Morsomme &amp; Remacle, 2016).&nbsp;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Les m\u00e9thodes chirurgicales propos\u00e9es pour f\u00e9miniser la voix doivent imp\u00e9rativement \u00eatre propos\u00e9es apr\u00e8s un essai logop\u00e9dique. En effet, selon le \u00ab Good Practice Guideline for Gender Dysphoria \u00bb (Wylie, 2014) une chirurgie pour f\u00e9minisation vocale peut \u00eatre propos\u00e9e, mais elle ne doit avoir lieu qu\u2019apr\u00e8s une intervention logop\u00e9dique et doit relever d\u2019une d\u00e9cision conjointe entre la patiente, le chirurgien ORL, le psychiatre, la\/ le logop\u00e8de. Ajoutons qu\u2019un suivi logop\u00e9dique est vivement conseill\u00e9 apr\u00e8s la chirurgie afin d\u2019optimiser les r\u00e9sultats chirurgicaux.&nbsp;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Ces m\u00e9thodes chirurgicales se basent sur l\u2019augmentation de la hauteur tonale (fo) \u2013un param\u00e8tre acoustique important pour associer une voix \u00e0 un genre f\u00e9minin (Owen &amp; Hancock, 2010); en raccourcissant les plis vocaux, en augmentant leur tension ou encore en r\u00e9tr\u00e9cissant le tractus vocal (Thomas &amp; MacMillan, 2013 ; Isshiki &amp; Tanabe, 1983 ; Remacle, Matar, Morsomme, Verduyckt, &amp; Lawson, 2011). Cependant, la fo \u00e0 elle seule, ne satisfait pas toujours suffisamment les femmes d\u00e9sireuses de f\u00e9miniser leur voix. En effet, plusieurs autres aspects comme les courbes intonatives, l\u2019articulation, l\u2019enrichissement des formants, le choix des mots, la mani\u00e8re de s\u2019exprimer, de bouger (dimension non verbale de la communication) sont autant de facteurs qui entrent en jeu dans la perception de f\u00e9minit\u00e9 vocale (Dacakis, 2000 ; Pasricha, Dacakis, &amp; Oates, 2008 ; Schwarz et al., 2016). Afin de r\u00e9pondre \u00e0 cette insatisfaction, des s\u00e9ances de f\u00e9minisation de la voix y compris de la communication orale sont propos\u00e9es par des logop\u00e8des sp\u00e9cialis\u00e9(e)s en voix. Ces s\u00e9ances visent \u00e0 travailler simultan\u00e9ment les diff\u00e9rents aspects de la voix pr\u00e9cit\u00e9s pour permettre aux femmes transgenres de s\u2019approprier une voix saine et une communication orale satisfaisante r\u00e9pondant \u00e0 leurs attentes. G\u00e9n\u00e9ralement, le potentiel vocal est examin\u00e9 lors de la premi\u00e8re consultation pour \u00e9tablir le plan th\u00e9rapeutique. Jusqu\u2019\u00e0 pr\u00e9sent, ce bilan vocal suit les recommandations de la Soci\u00e9t\u00e9 Europ\u00e9enne de Laryngologie (Dejonckere et al., 2001). Cependant, il est construit pour des patients dont la plainte concerne des troubles de la qualit\u00e9 vocale et non des personnes en demande de f\u00e9minisation vocale. Aussi, le praticien l\u2019adapte. Pour rappel, le bilan comprend l\u2019examen du plan glottique par vid\u00e9o-laryngo-stroboscopie (VLS), r\u00e9alis\u00e9e par un ORL, le recueil de donn\u00e9es objectives acoustiques (fo), niveau de pression sonore (NPS), indices de variabilit\u00e9 de la fr\u00e9quence (Jitter, d\u00e9viation standard) et du NPS (Shimmer) et a\u00e9rodynamiques (temps maximum phonatoire, capacit\u00e9 vitale, quotient phonatoire et pression sous-glottique estim\u00e9e). \u00c0 cela s\u2019ajoute le phon\u00e9togramme (\u00e9tendue vocale \u2013 fr\u00e9quence minimum et maximum \u2013 en fonction du niveau de pression sonore faible et fort) qui est envisag\u00e9 sous diff\u00e9rentes modalit\u00e9s de production (physiologique, langage spontan\u00e9, lecture de texte) et qui permet de visualiser l\u2019\u00e9tendue fr\u00e9quentielle et le niveau de pression sonore mobilis\u00e9s durant la parole (Morsomme &amp; Remacle, 2016). Le Voice Handicap Index est g\u00e9n\u00e9ralement remplac\u00e9 par le questionnaire \u00ab Trans Woman Voice Questionnaire \u00bb adapt\u00e9 et valid\u00e9 dans diff\u00e9rents contextes culturels et linguistiques. Cette \u00e9chelle est aussi utilis\u00e9e pour mesurer les exp\u00e9riences que vivent les personnes transgenres au quotidien. Elle peut aider \u00e0 \u00e9laborer ou adapter leur accompagnement logop\u00e9dique, en fonction de leurs perceptions et de leurs attentes respectives (Dacakis et al, 2013 ; Morsomme et al, 2019).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Afin d\u2019orienter le choix du traitement, il est essentiel pour le clinicien de comprendre la nature des changements d\u00e9sir\u00e9s par la patiente (augmentation mod\u00e9r\u00e9e ou excessive de la hauteur de la voix, modification du timbre et de la r\u00e9sonance, rapidit\u00e9 des r\u00e9sultats etc\u2026) (R\u00e9vis, 2016). Le traitement doit donc \u00eatre adapt\u00e9 et personnalis\u00e9 en fonction de chaque patiente (Pasternak &amp; Francis, 2019).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Il existe plusieurs approches th\u00e9rapeutiques en f\u00e9minisation vocale : l\u2019approche symptomatologique, la physiologique et l\u2019acoustique. L\u2019approche symptomatologique cible le comportement vocal le plus d\u00e9rangeant comme la hauteur tonale (fo). L\u2019approche physiologique se base sur les concepts d\u2019hygi\u00e8ne vocale et de comportement moteur vocal, elle cible l\u2019endurance et la capacit\u00e9 des syst\u00e8mes phonatoires et r\u00e9sonantiels. La troisi\u00e8me prend en consid\u00e9ration les param\u00e8tres acoustiques les plus d\u00e9terminants dans la perception du genre vocal (Dahl &amp; Mahler, 2019).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">En ce qui concerne la hauteur tonale, elle peut \u00eatre modifi\u00e9e par la th\u00e9rapie vocale et la chirurgie laryng\u00e9e. En revanche, cet indice acoustique ne repr\u00e9sente pas un crit\u00e8re absolu quant \u00e0 la satisfaction d\u2019une voix f\u00e9minine. Il est donc recommand\u00e9 de travailler l\u2019ensemble des param\u00e8tres communicationnels au sein de la th\u00e9rapie logop\u00e9dique, ces \u00e9l\u00e9ments n\u2019\u00e9tant pas modifi\u00e9s par la chirurgie. Des auteurs comme Morsomme et Remacle, A. (2016) et Astudillo (2019) mettent \u00e9galement en avant le d\u00e9bit de parole, la dur\u00e9e des phon\u00e8mes et la qualit\u00e9\u0301 vocale (le souffle) comme des param\u00e8tres \u00e0 cibler pour augmenter le degr\u00e9 de f\u00e9minit\u00e9 vocale. La m\u00e9thode Astudillo (2019) se base sur des principes th\u00e9oriques issus d\u2019autres th\u00e9rapies, telles que la Th\u00e9rapie M\u00e9lodique et Rythm\u00e9e (Van Eechkout et al., 1995), la M\u00e9thode Verbo-Tonale (Guberina, 1964, cit\u00e9 par Asp, 1985) et la m\u00e9thode Proprioceptive-Elastique (Lucchini et al., 2018). Elle permet aux personnes transgenres d\u2019exercer leur musculature laryng\u00e9e, faciale et articulatoire, d\u2019accentuer les contours intonatifs de la voix dans le but de rompre la monotonie fr\u00e9quentielle, de ralentir le d\u00e9bit de parole notamment en allongeant la dur\u00e9e de production des voyelles, d\u2019ajuster le niveau de pression sonore et enfin de travailler la fluidit\u00e9 du discours dans le but d\u2019aboutir \u00e0 une perception de f\u00e9minit\u00e9 optimale. Ces exercices permettent aux femmes transgenres de d\u00e9couvrir ou encore d\u2019augmenter leur potentiel vocal. Elles sont invit\u00e9es \u00e0 sortir de leur zone de confort \u00e0 travers la pratique d\u2019exercices d\u2019imitation et d\u2019exag\u00e9ration de la parole pour ensuite atteindre une parole plus f\u00e9minine. Actuellement, les informations concernant les techniques de prises en charge pour f\u00e9miniser la voix sont limit\u00e9es. Si la m\u00e9thode Astudillo semble \u00eatre pl\u00e9biscit\u00e9e par les nombreux t\u00e9moignages de clientes sur la toile, elle n\u2019a pas encore \u00e9t\u00e9 \u00e9prouv\u00e9e sur un plan scientifique. Aussi les \u00e9tudiants de l\u2019unit\u00e9 logop\u00e9die de la voix du d\u00e9partement logop\u00e9die de l\u2019universit\u00e9 de Li\u00e8ge s\u2019y sont int\u00e9ress\u00e9s et y ont consacr\u00e9 leurs travaux de m\u00e9moire de fin d\u2019\u00e9tudes sous la supervision de Dominique Morsomme. Les analyses se sont port\u00e9es sur des petits groupes ou sur des \u00e9tudes de cas appr\u00e9ciant ainsi le parcours unique de chaque participante. En effet, le choix d\u2019opter pour des protocoles exp\u00e9rimentaux \u00e0 cas unique aupr\u00e8s des personnes transgenres s\u2019explique notamment par une variabilit\u00e9 interindividuelle relativement importante entre les participantes.<\/span><\/p>\n\n\n<figure class=\"wp-block-image alignleft size-full\"><a href=\"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/Sans-titre-1.png\"><img decoding=\"async\" width=\"121\" height=\"112\" src=\"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/Sans-titre-1.png\" alt=\"\" class=\"wp-image-38715\"\/><\/a><\/figure>\n\n\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">N\u00e9anmoins, la premi\u00e8re synth\u00e8se de r\u00e9sultats que nous proposons rel\u00e8ve du m\u00e9moire r\u00e9alis\u00e9 par <strong>Coline Falla<\/strong> (2021) et concerne un groupe de femmes transgenres compar\u00e9es \u00e0 des femmes et des hommes cisgenres. Falla a cherch\u00e9 \u00e0 confronter les t\u00e9moignages positifs des femmes transgenres exprim\u00e9s sur la toile aux enregistrements effectu\u00e9s lors de leur s\u00e9ance de f\u00e9minisation vocale avec M. Astudillo. Le nombre de s\u00e9ances d\u2019une dur\u00e9e de 30 \u00e0 45 minutes variait entre 10 et 15. Les r\u00e9sultats reposent sur quatre groupes de donn\u00e9es dont deux constitu\u00e9s d\u2019une part par 12 femmes transgenres francophones et d\u2019autre part 10 femmes transgenres hispanophones, et deux autres constitu\u00e9s par 12 femmes cisgenres et 12 hommes cisgenres. Comme en t\u00e9moigne le tableau 1, les r\u00e9sultats obtenus au param\u00e8tre de fr\u00e9quence fondamentale parl\u00e9e (FFP) sont significativement sup\u00e9rieurs en postprise en charge pour les femmes transgenres hispanophones et francophones. Avant le traitement, la FFP m\u00e9diane des personnes transgenres est de 140 Hz pour les francophones et 133 Hz pour les hispanophones. Ces scores sont consid\u00e9r\u00e9s comme appartenant \u00e0 la plage fr\u00e9quentielle masculine (Davies et al., 2015). En post-traitement, les scores de la FFP m\u00e9diane des femmes transgenres francophones et hispanophones sont de respectivement 189 Hz et 198 Hz et donc significativement sup\u00e9rieurs \u00e0 ceux des hommes cisgenres (111 Hz), correspondant cette fois \u00e0 la plage fr\u00e9quentielle f\u00e9minine (Davies et al., 2015). La m\u00e9thode Astudillo contribue donc \u00e0 l\u2019augmentation significative de la FFP des femmes transgenres et ce toutes langues confondues. Ajoutons qu\u2019il est int\u00e9ressant d\u2019observer qu\u2019avant m\u00eame la prise en charge, les femmes transgenres produisent une FFP sup\u00e9rieure \u00e0 celle des hommes cisgenres. En effet, avant d\u2019entamer une prise en charge, certaines d\u2019entre elles s\u2019entra\u00eenent et tentent d\u2019atteindre leur id\u00e9al vocal f\u00e9minin.<\/span><\/p>\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/tableau-1.png\"><img fetchpriority=\"high\" decoding=\"async\" width=\"708\" height=\"327\" src=\"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/tableau-1.png\" alt=\"\" class=\"wp-image-38730\" srcset=\"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/tableau-1.png 708w, https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/tableau-1-510x236.png 510w, https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/tableau-1-300x139.png 300w\" sizes=\"(max-width: 708px) 100vw, 708px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image alignleft size-full\"><a href=\"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/Sans-titre-4.png\"><img loading=\"lazy\" decoding=\"async\" width=\"140\" height=\"142\" src=\"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/Sans-titre-4.png\" alt=\"\" class=\"wp-image-38742\" srcset=\"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/Sans-titre-4.png 140w, https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/Sans-titre-4-100x100.png 100w\" sizes=\"(max-width: 140px) 100vw, 140px\" \/><\/a><\/figure>\n\n\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Par ailleurs,<strong> Mathilde Neefs<\/strong> (2020) a r\u00e9alis\u00e9 son m\u00e9moire dans le cadre d\u2019une formation d\u00e9di\u00e9e \u00e0 la m\u00e9thode Astudillo. En effet, afin d\u2019illustrer la PEC, des ateliers ont \u00e9t\u00e9 organis\u00e9s et cinq femmes transgenres (sans passif logop\u00e9dique) ont accept\u00e9 d\u2019y prendre part. Elles ont chacune b\u00e9n\u00e9fici\u00e9 d\u2019un entra\u00eenement de 30 minutes r\u00e9alis\u00e9 par Mariela Astudillo. Un protocole de recueil de mesures subjectives et objectives a \u00e9t\u00e9 soumis aux participantes avant et apr\u00e8s l\u2019entra\u00eenement. L\u2019analyse des donn\u00e9es a \u00e9t\u00e9 r\u00e9alis\u00e9e (entre autres) sur deux t\u00e2ches de parole continue, l\u2019une consistant en la lecture du dialogue de Delattre (1966)\u00b2 et l\u2019autre une t\u00e2che de production de r\u00e9cit sur base de 6 images. Une augmentation des valeurs de plusieurs param\u00e8tres acoustiques en post-entra\u00eenement, quelle que soit la t\u00e2che a \u00e9t\u00e9 observ\u00e9e, sans pour autant obtenir de r\u00e9sultats significatifs sur le plan statistique (tableau 2). De plus, les donn\u00e9es issues de l\u2019analyse perceptive mettent en \u00e9vidence le gain de f\u00e9minit\u00e9 vocale \u00e0 court terme pour quatre des cinq participantes. Le comportement moteur vocal des participantes tend donc \u00e0 se modifier apr\u00e8s 30 minutes d\u2019entra\u00eenement, et ce changement se traduit dans les valeurs de certains param\u00e8tres acoustiques et perceptifs. Ce gain varie d\u2019une personne \u00e0 l\u2019autre. Chaque femme transgenre b\u00e9n\u00e9ficie diff\u00e9remment de l\u2019entra\u00eenement propos\u00e9 par Mariela Astudillo. Aussi, se sont-elles appropri\u00e9 le geste \u00e0 leur rythme sur un laps de temps relativement court.<\/span><\/p>\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/tableau-2.png\"><img loading=\"lazy\" decoding=\"async\" width=\"697\" height=\"308\" src=\"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/tableau-2.png\" alt=\"\" class=\"wp-image-38734\" srcset=\"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/tableau-2.png 697w, https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/tableau-2-510x225.png 510w, https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/tableau-2-300x133.png 300w\" sizes=\"(max-width: 697px) 100vw, 697px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image alignleft size-full\"><a href=\"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/Sans-titre-2.png\"><img loading=\"lazy\" decoding=\"async\" width=\"121\" height=\"106\" src=\"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/Sans-titre-2.png\" alt=\"\" class=\"wp-image-38719\"\/><\/a><\/figure>\n\n\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\"><strong>Aur\u00e9lie Gillot<\/strong> (2020), quant \u00e0 elle, a mesur\u00e9 l\u2019efficacit\u00e9 de 9 s\u00e9ances de f\u00e9minisation vocale prodigu\u00e9e par Mariella Astudillo chez une femme transgenre \u00e2g\u00e9e de 34 ans. Pr\u00e9cisons que les s\u00e9ances ont \u00e9t\u00e9 r\u00e9alis\u00e9es en t\u00e9l\u00e9pratique. La fo avant traitement sur un [a] tenu affichait la valeur m\u00e9diane de 158 Hz et sur parole continue (dialogue de Delattre) 155 Hz. Les r\u00e9sultats post prise en charge ont significativement augment\u00e9, la valeur m\u00e9diane de la fo sur le [a] atteignant 258 Hz et 242 Hz en parole continue. La satisfaction vocale de la participante a \u00e9t\u00e9 objectiv\u00e9e \u00e0 l\u2019aide du Trans Woman Voice questionnaire (Morsomme et al, 2019)\u00b3 et s\u2019est av\u00e9r\u00e9e significativement am\u00e9lior\u00e9e, le score passant de 69\/120 \u00e0 39\/120 (\u2260 30), sachant que plus le score est \u00e9lev\u00e9 plus la plainte est importante.<\/span><\/p>\n\n\n<figure class=\"wp-block-image alignleft size-full\"><a href=\"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/Sans-titre-3.png\"><img loading=\"lazy\" decoding=\"async\" width=\"125\" height=\"122\" src=\"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/Sans-titre-3.png\" alt=\"\" class=\"wp-image-38723\"\/><\/a><\/figure>\n\n\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Enfin, l\u2019objectif du travail d\u2019<strong>Elina Godelle<\/strong> (2020) \u00e9tait de mesurer l\u2019efficacit\u00e9 de 10 s\u00e9ances de th\u00e9rapie vocale chez une femme transgenre \u00e2g\u00e9e de 37 ans. Cette fois, les s\u00e9ances ont \u00e9t\u00e9 assur\u00e9es par une logop\u00e8de form\u00e9e fra\u00eechement \u00e0 la m\u00e9thode Astudillo et r\u00e9alis\u00e9e en t\u00e9l\u00e9pratique comme le pr\u00e9conise la m\u00e9thode. Les r\u00e9sultats repris dans le tableau 3 mettent en \u00e9vidence un l\u00e9ger effet sur l\u2019acquisition des patterns vocaux f\u00e9minins de la participante notamment par une augmentation des valeurs de fr\u00e9quence fondamentale et de dynamique fr\u00e9quentielle exprim\u00e9e en demi-tons. Notons que la t\u00e2che de r\u00e9cit sur images a mieux permis \u00e0 la participante de mobiliser des fr\u00e9quences du registre f\u00e9minin. De m\u00eame, le ressenti de la participante par rapport \u00e0 sa voix s\u2019est am\u00e9lior\u00e9 en fin de prise en charge passant de 116\/120 \u00e0 71\/120 (\u2260 45).<\/span><\/p>\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/tableau-3.png\"><img loading=\"lazy\" decoding=\"async\" width=\"714\" height=\"308\" src=\"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/tableau-3.png\" alt=\"\" class=\"wp-image-38738\" srcset=\"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/tableau-3.png 714w, https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/tableau-3-510x220.png 510w, https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/tableau-3-300x129.png 300w\" sizes=\"(max-width: 714px) 100vw, 714px\" \/><\/a><\/figure>\n\n\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La synth\u00e8se des \u00e9tudes rapport\u00e9es ci-dessus n\u2019est pas exhaustive. Les m\u00e9morantes se sont distingu\u00e9es les unes des autres par la formulation d\u2019hypoth\u00e8ses originales en lien avec leurs \u00e9tudes respectives. Nous ne faisons ici que rapporter une petite partie de leur travail et principalement orient\u00e9e sur des valeurs fr\u00e9quentielles. Si vous d\u00e9sirez en savoir plus, il vous est loisible d\u2019acc\u00e9der aux travaux sur la plateforme institutionnelle suivante : https:\/\/matheo.uliege.be en introduisant le nom des autrices dans le moteur de recherche apparaissant sous l\u2019onglet Feuilleter\/Rechercher. Nous pr\u00e9cisons \u00e9galement que chaque m\u00e9moire a re\u00e7u l\u2019approbation du comit\u00e9 d\u2019\u00e9thique de la Facult\u00e9 de Psychologie, Logop\u00e9die et Sciences de l\u2019\u00e9ducation. Les r\u00e9sultats obtenus aux diff\u00e9rentes m\u00e9thodologies appliqu\u00e9es \u00e0 la m\u00e9thode Astudillo nous confortent dans l\u2019id\u00e9e que les param\u00e8tres travaill\u00e9s d\u00e9bouchent sur une modification du comportement moteur vocal en faveur d\u2019une perception de f\u00e9minit\u00e9 dans la voix. L\u2019ensemble des \u00e9tudes cit\u00e9es tout au long de cet article soulignent l\u2019importance du travail logop\u00e9dique dans le processus de f\u00e9minisation vocale qui se base sur les variations acoustiques de la fo, du niveau de pression sonore, de la dur\u00e9e (Di Cristo, 2013). Une telle d\u00e9marche consiste aussi en un accompagnement global de la personne transgenre afin d\u2019assurer un meilleur ajustement des aspects verbaux et non verbaux au genre d\u00e9sir\u00e9.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Au-del\u00e0 du message qu\u2019elle porte, la voix participe ind\u00e9niablement \u00e0 notre identit\u00e9 (Revis, 2019). Aussi, l\u2019accompagnement des personnes transgenres dans la recherche de leur voix s\u2019av\u00e8re pertinent et aboutit \u00e0 des r\u00e9sultats satisfaisants sur le plan vocal. Il r\u00e9pond \u00e0 un besoin vital et un droit essentiel pour chacune de ces personnes de se sentir \u00e0 l\u2019aise dans sa communication orale, que celle-ci se d\u00e9roule dans la sph\u00e8re priv\u00e9e, sociale ou encore professionnelle.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Cet article vise \u00e0 \u00e9clairer vos connaissances dans le domaine de f\u00e9minisation vocale dont l\u2019efficacit\u00e9 reste encore un champ d\u2019investigation trop peu explor\u00e9. Les \u00e9tudes et les travaux mentionn\u00e9s laissent \u00e0 penser que la logop\u00e9die de la voix offre de belles perspectives de travail et d\u2019accompagnement de la personne en recherche de f\u00e9minit\u00e9 vocale. Nous souhaitons susciter des vocations afin que chaque personne d\u00e9sireuse de f\u00e9miniser sa voix puisse acc\u00e9der facilement \u00e0 un cabinet de logop\u00e9die proche de son domicile, car m\u00eame si la t\u00e9l\u00e9pratique est une option, certaines d\u2019entre elles souhaitent rencontrer de visu leur th\u00e9rapeute.<\/span><\/p>\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<p style=\"text-align: justify;\"><i><span style=\"font-weight: 400;\">\u00b9 Si en Belgique, les personnes transgenres s\u2019adressent \u00e0 une logop\u00e8de sp\u00e9cialis\u00e9e en voix, elles sont r\u00e9f\u00e9r\u00e9es comme des patientes et peuvent pr\u00e9tendre \u00e0 un remboursement mutuelle de leurs s\u00e9ances de prise en soin. Le cadre dans lequel travaille Mariela Astudillo est diff\u00e9rent, toute personne d\u00e9sireuse de modifier sa voix peut acheter un forfait de s\u00e9ances. Celles-ci sont alors des clientes et non des patientes.<\/span><\/i><\/p>\n<p style=\"text-align: justify;\"><i><span style=\"font-weight: 400;\">* Cisgenre se dit d\u2019une personne dont l\u2019identit\u00e9 de genre (masculin ou f\u00e9minin) correspond au sexe avec lequel elle est n\u00e9e contrairement \u00e0 transgenre.<\/span><\/i><\/p>\n<p style=\"text-align: justify;\"><i><span style=\"font-weight: 400;\">\u00b2 Pr\u00e9cisons que le dialogue de Delattre (1966) a l\u2019avantage de contenir les diff\u00e9rentes intonations de base du fran\u00e7ais.<\/span><\/i><\/p>\n<p style=\"text-align: justify;\"><i><span style=\"font-weight: 400;\">\u00b3 M\u00eame si dans l\u2019article de Morsomme et al (2019), vous lirez le titre \u00ab Transsexual Voice Questionnaire male to female \u00bb, il est plus adapt\u00e9 d\u2019adopter la formule Trans Woman Voice Questionnaire.<\/span><\/i><\/p>\n\n\n<div style=\"height:23px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<h5><span style=\"color: #fb115f;\"><a style=\"color: #fb115f;\"><strong>Bibliographie<\/strong>&nbsp;:<\/a><\/span><\/h5>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">American Psychological Association (APA). A glossary: Defining transgender terms. 2020. https:\/\/www.apa.org\/monitor\/2018\/09\/cecorner-glossary\/. Astudillo, M. (2019). La f\u00e9minisation de la voix : Introduction \u00e0 la m\u00e9thode Astudillo. Almeria, Espagne : Editorial C\u00edrculo Rojo. Asp, C. W. (1985). The verbotonal method for management of young, hearing-impaired children. Ear and Hearing, 6(1), 39\u201342. Azul, D., Nygren, U., Sodersten, M., Rube-Neuschaefer, C., (2017). Transmaculine people\u2019s voice function: a review of the currently available evidence. Journal of voice. 31(2) : 261.e9-261.e23. Bourgeois M. -L. (1980), \u00ab Transsexualisme, dysphorie de genre et troubles de l\u2019identit\u00e9 sexuelle. Une exp\u00e9rience am\u00e9ricaine \u00bb, Ann Med Psychol, 138, 472-80. Coleman, E., Bockting, W., Botzer, M., Cohen-Kettenis, P., DeCuypere, G., Feldman, J., &#8230; Zucker, K. (2012). Standards of care for the health of transsexual, transgender, and gender-nonconforming people, Version 7. International Journal of Transgenderism, 13(4), 165\u2013232. Dacakis, G. (2000). Long-term maintenance of fundamental frequency increases in male-to- female transsexuals. Journal of Voice, 14(4), 549\u2013 556. Dacakis, G., Davies, S., Oates, J.M., Douglas, J.M., &amp; Johnston J.R. (2013). Development and preliminary evaluation of the Transsexual Voice Questionnaire for male-to-female transsexuals. Journal of Voice, 27(3), 312\u2013320. Dahl, K. L., &amp; Mahler, L. A. (2019). Acoustic features of transfeminine voices and perceptions of voice femininity. Journal of Voice. Davies, S., Papp, V. G., &amp; Antoni, C. (2015). Voice and communication change for gender nonconforming individuals: Giving voice to the person inside. International Journal of Transgenderism, 16 (3), 117-159. Dejonckere, P. H., Bradley, P., Clemente, P., Cornut, G., CrevierBuchman, L., Friedrich, G., Woisard, V. (2001). A basic protocol for functional assessment of voice pathology, especially for investigating the efficacy of (phonosurgical) treatments and evaluating new assessment techniques. European Archives of Oto-Rhino-Laryngology, 258(2), 77\u201382. Delattre, P. (1966). Les dix intonations de base du fran\u00e7ais. The French Review, 40(1), 1-14. Di Cristo, A. (2013). La prosodie de la parole. De Boeck Superieur. Falla, M. (2021). F\u00e9minisation vocale: mesure de l\u2019efficacit\u00e9 de la m\u00e9thode Astudillo et comparaison transgenres-cisgenres. (M\u00e9moire de Master, non publi\u00e9). Universit\u00e9 de Li\u00e8ge, Li\u00e8ge, Belgique. Gillot A. (2020). \u00c9tude de cas : mesure de l\u2019efficacit\u00e9 de la m\u00e9thode Astudillo dans le cadre de la prise en charge logop\u00e9dique pour f\u00e9minisation vocale. (M\u00e9moire de Master, non publi\u00e9). Universit\u00e9 de Li\u00e8ge, Li\u00e8ge, Belgique. Godelle E. (2020). Application de la m\u00e9thode Astudillo pour f\u00e9miniser la voix : \u00e9tude de cas. (M\u00e9moire de Master, non publi\u00e9). Universit\u00e9 de Li\u00e8ge, Li\u00e8ge, Belgique. Hancock, A., &amp; Helenius, L. (2012). Adolescent male-to-female transgender voice and communication therapy. Journal of Communication Disorders, 45(5), 313-324. Isshiki, N. T., &amp; Tanabe, M. (1983). Surgical alteration of the vocal pitch. J Otolaryngol., 12, 335\u2013340. Lechien, J.R, Delvaux, V., Huet, K., Khalife, M., Piccaluga, M., Harmegnies, B., &amp; Saussez, S. (2014). Transgender voice and communication treatment: Review of the literature. Revue de Laryngologie Otologie Rhinologie, 135, 97-103. Lucchini, E., Ricci Maccarini, A., Bissoni, E., Borragan, M., Agudo, M., Gonzalez, M. J., Romizi, V., Schindler, A., Behlau, M., Murry, T., &amp; Borragan, A. (2018). Voice improvement in patients with functional dysphonia treated with the Proprioceptive-Elastic (PROEL) method. Journal of voice, 32(2), 209-215. doi: 10.1016\/j.jvoice.2017.05.018 Morsomme, D., &amp; Remacle, A. (2016). F\u00e9miniser la voix. In C. KleineDallant (Ed.), De la voix parl\u00e9e au chant : Bilans, r\u00e9\u00e9ducations, pathologies de la voix parl\u00e9e et chant\u00e9e. (pp. 327-340). Klein-Dallant. Morsomme, D., Revis, J., &amp; Thomas, E. (2019). Translation, Adaptation, and Preliminary Validation of Dacakis and Davies\u2019 \u201cTranssexual Voice Questionnaire (Male to Female)\u201d in French. Journal of Voice, 33(5), 807. e13\u2013807.e24. Neefs M. (2020). Mesure \u00e0 court terme de l\u2019efficacit\u00e9 de la m\u00e9thode Astudillo dans le cadre d\u2019une pratique formative en f\u00e9minisation vocale. (M\u00e9moire de Master, non publi\u00e9). Universit\u00e9 de Li\u00e8ge, Li\u00e8ge, Belgique. Owen, K., &amp; Hancock, A. B. (2010). The role of self-and listener perceptions of femininity in voice therapy. International Journal of Transgenderism, 12, 272-284. Pasricha, N., Dacakis, G., &amp; Oates, J. (2008). Communicative satisfaction of male-to-female transsexuals\u2019 Communicative satisfaction of maleto-female transsexuals. Logopedics Phoniatrics Vocology, 33, 25\u201334. Pasternak, K., &amp; Francis, D. O. (2019). An update on treatment of voice-gender incongruence by otolaryngologists and speech-language pathologists. Current Opinion in Otolaryngology and Head and Neck Surgery, 27(6), 475-481. doi: 10.1097\/MOO.0000000000000582 P\u00e9piot, E. (2013). Voix de femmes, voix d\u2019hommes : Diff\u00e9rences acoustiques, identification du genre par la voix et implications psycholinguistiques chez les locuteurs anglophones et francophones (Th\u00e8se de doctorat). Universit\u00e9 Paris VIII &#8211; Vincennes-Saint Denis, Paris, France. Remacle, M., Matar, N., Morsomme, D., Verduyckt, I., &amp; Lawson, G. (2011). Glottoplasty for male-to-female transsexualism: Voice results. Journal of Voice, 25(1), 120\u2013123. R\u00e9vis, J. (2019). La prise en charge orthophonique p\u00e9ri-op\u00e9ratoire dans le cadre d\u2019une chirurgie de f\u00e9minisation vocale. Voix et transidentit\u00e9s : La prise en charge vocale des personnes transgenres (pp.175-190). Isbergues, France : OrthoEdition. Schwarz, K., Martha, A., Fontanari, V., Mueller, A., Costa, A. B., Soll, B., &#8230; Alegre, P. (2016). Transsexual Voice Questionnaire for Male-tofemale Brazilian Transsexual People. Journal of Voice, 31(1), 15\u201320. https:\/\/doi.org\/10.1016\/j.jvoice.2016.02.012 S\u00f6dersten, M., Nygren, U., Herteg\u00e5rd, S., &amp; Dhejne, C. (2019). A multidisciplinary approach to transgender health. In Adler, R. K., Hirsch, S., &amp; Pickering, J. (Eds.), Voice and 85 communication therapy for the transgender\/gender diverse client: A comprehensive clinical guide (3rd ed., pp. 1-19). Plural Publishing. Thomas JP, Macmillan C. Feminization laryngoplasty: assessment of surgical pitch elevation. Eur Arch Oto-Rhino-Laryngol Off J Eur Fed Oto-Rhino-Laryngol Soc EUFOS Affil Ger Soc Oto-Rhino-Laryngol &#8211; Head Neck Surg. sept 2013;270(10):2695 700. T\u2019Sjoen, G., Arcelus, J., Gooren, L., Klink, D. T., &amp; Tangpricha, V. (2019). Endocrinology of Transgender Medicine. Endocrine Reviews, 40(1), 97- 117. Van Eeckhout, P., Backchine, S., Chomel De Varagnes, S., Francois, C., Belin, P., &amp; Samson, Y. (1995). La th\u00e9rapie m\u00e9lodique et rythm\u00e9e. R\u00e9\u00e9ducation Orthophonique, 33, 379-399. Wylie, K., Barrett, J., Besser, M., Bouman, W. P., Bridgman, M., Clayton, A., Green, R., Hamilton, M., Hines, M., Ivbijaro, G., Khoosal, D., Lawrence, A., Lenihan, P., Loewenthal,D., Ralph, D., Reed, T., Stevens, J., Terry, T., Thom, B., &#8230; Ward, D. (2014). Good practice guidelines for the assessment and treatment of adults with gender dysphoria. Sexual and Relationship Therapy, 29, 154-214.<\/span><\/p>\n\n\n<div style=\"height:23px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button alignleft is-style-fill\"><a class=\"wp-block-button__link has-background\" href=\"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/UI-5-2021-JaberMorsomme.pdf\" style=\"background-color:#fc0064\" target=\"_blank\" rel=\"noreferrer noopener\">T\u00c9L\u00c9CHARGER LE PDF ORIGINAL<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Batoul JABER\u00b9,\u00b2 &amp; Dominique MORSOMME\u00b2, \u00b9Universit\u00e9 Saint Joseph de Beyrouth, Liban&nbsp;; \u00b2Research Unit for a life-Course perspective on Health and Education, Universit\u00e9 de Li\u00e8ge, Belgique Article publi\u00e9 initialement sur UPLF https:\/\/www.uplf.be\/ &#8211;&nbsp;IU n\u00ba 5\/2021. Nous tenons \u00e0 remercier chaleureusement les \u00e9tudiants pour les \u00e9tudes qu\u2019ils ont men\u00e9es dans le cadre de leur m\u00e9moire. Sans eux, [&hellip;]<\/p>\n","protected":false},"author":367,"featured_media":38622,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[58,313],"tags":[414,247,161],"class_list":["post-38726","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrainement-vocal","category-methode-astudillo","tag-entrainementvocal","tag-feminisation-de-la-voix","tag-methode-astudillo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v19.6 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>F\u00e9miniser la communication orale et plus sp\u00e9cifiquement la voix | Revue Digitale \u00c9motus | Femivoz<\/title>\n<meta name=\"description\" content=\"Cet article vise \u00e0 \u00e9clairer vos connaissances dans le domaine de f\u00e9minisation vocale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/femivoz.es\/fr\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u00e9miniser la communication orale et plus sp\u00e9cifiquement la voix\" \/>\n<meta property=\"og:description\" content=\"Cet article vise \u00e0 \u00e9clairer vos connaissances dans le domaine de f\u00e9minisation vocale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/femivoz.es\/fr\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\/\" \/>\n<meta property=\"og:site_name\" content=\"FEMIVOZ | Mariela Astudillo | Vocologiste &amp; Vocal Trainer\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/femivoz\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-05T15:47:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-08T21:57:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/UPLF.png\" \/>\n\t<meta property=\"og:image:width\" content=\"828\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"FEMIVOZ\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@femivoz\" \/>\n<meta name=\"twitter:site\" content=\"@femivoz\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"FEMIVOZ\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"20 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/femivoz.es\\\/fr\\\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/femivoz.es\\\/fr\\\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\\\/\"},\"author\":{\"name\":\"FEMIVOZ\",\"@id\":\"https:\\\/\\\/femivoz.es\\\/fr\\\/#\\\/schema\\\/person\\\/bbadb0ea882eac10f0d7540a4621792c\"},\"headline\":\"F\u00e9miniser la communication orale et plus sp\u00e9cifiquement la voix\",\"datePublished\":\"2022-04-05T15:47:37+00:00\",\"dateModified\":\"2022-06-08T21:57:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/femivoz.es\\\/fr\\\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\\\/\"},\"wordCount\":4192,\"publisher\":{\"@id\":\"https:\\\/\\\/femivoz.es\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/femivoz.es\\\/fr\\\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/femivoz.es\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/UPLF.png\",\"keywords\":[\"#ENTRA\u00ceNEMENTVOCAL\",\"#F\u00c9MINISATIONDELAVOIX\",\"#M\u00c9THODEASTUDILLO\"],\"articleSection\":[\"ENTRA\u00ceNEMENT VOCAL\",\"M\u00c9THODE ASTUDILLO\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/femivoz.es\\\/fr\\\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\\\/\",\"url\":\"https:\\\/\\\/femivoz.es\\\/fr\\\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\\\/\",\"name\":\"F\u00e9miniser la communication orale et plus sp\u00e9cifiquement la voix | Revue Digitale \u00c9motus | Femivoz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/femivoz.es\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/femivoz.es\\\/fr\\\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/femivoz.es\\\/fr\\\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/femivoz.es\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/UPLF.png\",\"datePublished\":\"2022-04-05T15:47:37+00:00\",\"dateModified\":\"2022-06-08T21:57:54+00:00\",\"description\":\"Cet article vise \u00e0 \u00e9clairer vos connaissances dans le domaine de f\u00e9minisation vocale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/femivoz.es\\\/fr\\\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/femivoz.es\\\/fr\\\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/femivoz.es\\\/fr\\\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\\\/#primaryimage\",\"url\":\"https:\\\/\\\/femivoz.es\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/UPLF.png\",\"contentUrl\":\"https:\\\/\\\/femivoz.es\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/UPLF.png\",\"width\":828,\"height\":315,\"caption\":\"UPLF\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/femivoz.es\\\/fr\\\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/femivoz.es\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F\u00e9miniser la communication orale et plus sp\u00e9cifiquement la voix\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/femivoz.es\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/femivoz.es\\\/fr\\\/\",\"name\":\"FEMIVOZ | Mariela Astudillo | Vocologiste &amp; Vocal Trainer\",\"description\":\"F\u00e9minisation de la voix et autres entra\u00eenements vocaux LGBTQIA+\",\"publisher\":{\"@id\":\"https:\\\/\\\/femivoz.es\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/femivoz.es\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/femivoz.es\\\/fr\\\/#organization\",\"name\":\"FEMIVOZ\",\"url\":\"https:\\\/\\\/femivoz.es\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/femivoz.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/femivoz.es\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Logo-femivoz-2018-HD-B.png\",\"contentUrl\":\"https:\\\/\\\/femivoz.es\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Logo-femivoz-2018-HD-B.png\",\"width\":2210,\"height\":658,\"caption\":\"FEMIVOZ\"},\"image\":{\"@id\":\"https:\\\/\\\/femivoz.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/femivoz\",\"https:\\\/\\\/x.com\\\/femivoz\",\"https:\\\/\\\/www.instagram.com\\\/femivoz\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/femivoz-mariela-astudillo-1401ab21a\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC33Zf-WKvD_Gd_tosA47SFw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/femivoz.es\\\/fr\\\/#\\\/schema\\\/person\\\/bbadb0ea882eac10f0d7540a4621792c\",\"name\":\"FEMIVOZ\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9bb57af3a3b0b0c7b54a4ccc4aff34bf27533559ead028e1fe79c3e8dd78504d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9bb57af3a3b0b0c7b54a4ccc4aff34bf27533559ead028e1fe79c3e8dd78504d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9bb57af3a3b0b0c7b54a4ccc4aff34bf27533559ead028e1fe79c3e8dd78504d?s=96&d=mm&r=g\",\"caption\":\"FEMIVOZ\"},\"url\":\"https:\\\/\\\/femivoz.es\\\/fr\\\/author\\\/femivoz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"F\u00e9miniser la communication orale et plus sp\u00e9cifiquement la voix | Revue Digitale \u00c9motus | Femivoz","description":"Cet article vise \u00e0 \u00e9clairer vos connaissances dans le domaine de f\u00e9minisation vocale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/femivoz.es\/fr\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\/","og_locale":"fr_FR","og_type":"article","og_title":"F\u00e9miniser la communication orale et plus sp\u00e9cifiquement la voix","og_description":"Cet article vise \u00e0 \u00e9clairer vos connaissances dans le domaine de f\u00e9minisation vocale.","og_url":"https:\/\/femivoz.es\/fr\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\/","og_site_name":"FEMIVOZ | Mariela Astudillo | Vocologiste &amp; Vocal Trainer","article_publisher":"https:\/\/www.facebook.com\/femivoz","article_published_time":"2022-04-05T15:47:37+00:00","article_modified_time":"2022-06-08T21:57:54+00:00","og_image":[{"width":828,"height":315,"url":"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/UPLF.png","type":"image\/png"}],"author":"FEMIVOZ","twitter_card":"summary_large_image","twitter_creator":"@femivoz","twitter_site":"@femivoz","twitter_misc":{"\u00c9crit par":"FEMIVOZ","Dur\u00e9e de lecture estim\u00e9e":"20 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/femivoz.es\/fr\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\/#article","isPartOf":{"@id":"https:\/\/femivoz.es\/fr\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\/"},"author":{"name":"FEMIVOZ","@id":"https:\/\/femivoz.es\/fr\/#\/schema\/person\/bbadb0ea882eac10f0d7540a4621792c"},"headline":"F\u00e9miniser la communication orale et plus sp\u00e9cifiquement la voix","datePublished":"2022-04-05T15:47:37+00:00","dateModified":"2022-06-08T21:57:54+00:00","mainEntityOfPage":{"@id":"https:\/\/femivoz.es\/fr\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\/"},"wordCount":4192,"publisher":{"@id":"https:\/\/femivoz.es\/fr\/#organization"},"image":{"@id":"https:\/\/femivoz.es\/fr\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\/#primaryimage"},"thumbnailUrl":"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/UPLF.png","keywords":["#ENTRA\u00ceNEMENTVOCAL","#F\u00c9MINISATIONDELAVOIX","#M\u00c9THODEASTUDILLO"],"articleSection":["ENTRA\u00ceNEMENT VOCAL","M\u00c9THODE ASTUDILLO"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/femivoz.es\/fr\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\/","url":"https:\/\/femivoz.es\/fr\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\/","name":"F\u00e9miniser la communication orale et plus sp\u00e9cifiquement la voix | Revue Digitale \u00c9motus | Femivoz","isPartOf":{"@id":"https:\/\/femivoz.es\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/femivoz.es\/fr\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\/#primaryimage"},"image":{"@id":"https:\/\/femivoz.es\/fr\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\/#primaryimage"},"thumbnailUrl":"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/UPLF.png","datePublished":"2022-04-05T15:47:37+00:00","dateModified":"2022-06-08T21:57:54+00:00","description":"Cet article vise \u00e0 \u00e9clairer vos connaissances dans le domaine de f\u00e9minisation vocale.","breadcrumb":{"@id":"https:\/\/femivoz.es\/fr\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/femivoz.es\/fr\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/femivoz.es\/fr\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\/#primaryimage","url":"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/UPLF.png","contentUrl":"https:\/\/femivoz.es\/wp-content\/uploads\/2022\/04\/UPLF.png","width":828,"height":315,"caption":"UPLF"},{"@type":"BreadcrumbList","@id":"https:\/\/femivoz.es\/fr\/feminiser-la-communication-orale-et-plus-specifiquement-la-voix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/femivoz.es\/fr\/"},{"@type":"ListItem","position":2,"name":"F\u00e9miniser la communication orale et plus sp\u00e9cifiquement la voix"}]},{"@type":"WebSite","@id":"https:\/\/femivoz.es\/fr\/#website","url":"https:\/\/femivoz.es\/fr\/","name":"FEMIVOZ | Mariela Astudillo | Vocologiste &amp; Vocal Trainer","description":"F\u00e9minisation de la voix et autres entra\u00eenements vocaux LGBTQIA+","publisher":{"@id":"https:\/\/femivoz.es\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/femivoz.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/femivoz.es\/fr\/#organization","name":"FEMIVOZ","url":"https:\/\/femivoz.es\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/femivoz.es\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/femivoz.es\/wp-content\/uploads\/2018\/05\/Logo-femivoz-2018-HD-B.png","contentUrl":"https:\/\/femivoz.es\/wp-content\/uploads\/2018\/05\/Logo-femivoz-2018-HD-B.png","width":2210,"height":658,"caption":"FEMIVOZ"},"image":{"@id":"https:\/\/femivoz.es\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/femivoz","https:\/\/x.com\/femivoz","https:\/\/www.instagram.com\/femivoz\/","https:\/\/www.linkedin.com\/in\/femivoz-mariela-astudillo-1401ab21a\/","https:\/\/www.youtube.com\/channel\/UC33Zf-WKvD_Gd_tosA47SFw"]},{"@type":"Person","@id":"https:\/\/femivoz.es\/fr\/#\/schema\/person\/bbadb0ea882eac10f0d7540a4621792c","name":"FEMIVOZ","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9bb57af3a3b0b0c7b54a4ccc4aff34bf27533559ead028e1fe79c3e8dd78504d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9bb57af3a3b0b0c7b54a4ccc4aff34bf27533559ead028e1fe79c3e8dd78504d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9bb57af3a3b0b0c7b54a4ccc4aff34bf27533559ead028e1fe79c3e8dd78504d?s=96&d=mm&r=g","caption":"FEMIVOZ"},"url":"https:\/\/femivoz.es\/fr\/author\/femivoz\/"}]}},"_links":{"self":[{"href":"https:\/\/femivoz.es\/fr\/wp-json\/wp\/v2\/posts\/38726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/femivoz.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/femivoz.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/femivoz.es\/fr\/wp-json\/wp\/v2\/users\/367"}],"replies":[{"embeddable":true,"href":"https:\/\/femivoz.es\/fr\/wp-json\/wp\/v2\/comments?post=38726"}],"version-history":[{"count":0,"href":"https:\/\/femivoz.es\/fr\/wp-json\/wp\/v2\/posts\/38726\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/femivoz.es\/fr\/wp-json\/wp\/v2\/media\/38622"}],"wp:attachment":[{"href":"https:\/\/femivoz.es\/fr\/wp-json\/wp\/v2\/media?parent=38726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/femivoz.es\/fr\/wp-json\/wp\/v2\/categories?post=38726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/femivoz.es\/fr\/wp-json\/wp\/v2\/tags?post=38726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}